{"id":396940,"count":3,"description":"","link":"https:\/\/sites.nd.edu\/niovino\/category\/the-methodology\/","name":"The Methodology","slug":"the-methodology","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/sites.nd.edu\/niovino\/wp-json\/wp\/v2\/categories\/396940","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.nd.edu\/niovino\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/sites.nd.edu\/niovino\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/sites.nd.edu\/niovino\/wp-json\/wp\/v2\/posts?categories=396940"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}